{"id":1296,"date":"2024-05-30T11:17:29","date_gmt":"2024-05-30T09:17:29","guid":{"rendered":"https:\/\/nayada.eu\/shop\/peeling-de-cafe\/"},"modified":"2024-05-30T11:17:29","modified_gmt":"2024-05-30T09:17:29","slug":"peeling-de-cafe","status":"publish","type":"product","link":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/","title":{"rendered":"Peeling de caf\u00e9"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Peeling de caf\u00e9 &#8211; este jab\u00f3n de caf\u00e9 favorece la circulaci\u00f3n sangu\u00ednea y el drenaje linf\u00e1tico, lo que a su vez mejora la textura, el color y la \u0435\u043b\u0430\u0441\u0442\u0438\u0447\u043d\u0456\u0441\u0442\u044c\ud83d\ude4c\ud83c\udffc de la piel.<br \/>\nPara un mejor efecto, le a\u00f1adimos semillas de amapola, que tambi\u00e9n exfolia las c\u00e9lulas muertas y ayuda a renovar el estrato c\u00f3rneo\ud83e\udd29.<br \/>\nY tambi\u00e9n tenemos jab\u00f3n con lufa, es una esponja de origen natural \ud83c\udf3f.<\/p>\n<p>Este jab\u00f3n masajea y exfolia a\u00fan mejor la piel, por lo que es perfecto para quienes gustan de un efecto brillante.<\/p>\n<p>El masaje acelera la circulaci\u00f3n sangu\u00ednea y el flujo linf\u00e1tico, lo que a su vez elimina el exceso de agua del cuerpo, y las c\u00e9lulas reciben m\u00e1s ox\u00edgeno.<\/p>\n<p>Este procedimiento alivia la fatiga, ayuda a calmarse, relajarse y sintonizar con un sue\u00f1o reparador \ud83d\ude34.<\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<p>Aceite de hueso de albaricoque saponificado, aceite de coco, aceite de almendras dulces, aceite de ricino, caf\u00e9 molido, di\u00f3xido de titanio, cacao en polvo, pigmento mineral, mica composici\u00f3n arom\u00e1tica.<\/p>\n<p>Peso: ~100g (el peso del jab\u00f3n puede variar +\/-10g)<\/p>\n","protected":false},"featured_media":1097,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[99],"product_tag":[106,100,104,96,103,101,97,105,98,102],"class_list":{"0":"post-1296","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-jabones","7":"product_tag-bio-soap-es","8":"product_tag-creamy-soap-es","9":"product_tag-essential-oil-soap-es","10":"product_tag-handmade-soap-es","11":"product_tag-natural-cosmetic-es","12":"product_tag-natural-design-es","13":"product_tag-natural-soap-es","14":"product_tag-organic-soap-es","15":"product_tag-soap-es","16":"product_tag-vegan-soap-es","17":"product_shipping_class-soap-es","19":"first","20":"outofstock","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Peeling de caf\u00e9 - nayada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peeling de caf\u00e9\" \/>\n<meta property=\"og:description\" content=\"Peeling de caf\u00e9 - este jab\u00f3n de caf\u00e9 favorece la circulaci\u00f3n sangu\u00ednea y el drenaje linf\u00e1tico, lo que a su vez mejora la textura, el color y la \u0435\u043b\u0430\u0441\u0442\u0438\u0447\u043d\u0456\u0441\u0442\u044c\ud83d\ude4c\ud83c\udffc de la piel. Para un mejor efecto, le a\u00f1adimos semillas de amapola, que tambi\u00e9n exfolia las c\u00e9lulas muertas y ayuda a renovar el estrato c\u00f3rneo\ud83e\udd29. Y tambi\u00e9n tenemos jab\u00f3n con lufa, es una esponja de origen natural \ud83c\udf3f.  Este jab\u00f3n masajea y exfolia a\u00fan mejor la piel, por lo que es perfecto para quienes gustan de un efecto brillante.  El masaje acelera la circulaci\u00f3n sangu\u00ednea y el flujo linf\u00e1tico, lo que a su vez elimina el exceso de agua del cuerpo, y las c\u00e9lulas reciben m\u00e1s ox\u00edgeno.  Este procedimiento alivia la fatiga, ayuda a calmarse, relajarse y sintonizar con un sue\u00f1o reparador \ud83d\ude34.  Ingredientes:  Aceite de hueso de albaricoque saponificado, aceite de coco, aceite de almendras dulces, aceite de ricino, caf\u00e9 molido, di\u00f3xido de titanio, cacao en polvo, pigmento mineral, mica composici\u00f3n arom\u00e1tica.  Peso: ~100g (el peso del jab\u00f3n puede variar +\/-10g)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/\" \/>\n<meta property=\"og:site_name\" content=\"nayada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/\",\"url\":\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/\",\"name\":\"Peeling de caf\u00e9 - nayada\",\"isPartOf\":{\"@id\":\"https:\/\/nayada.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp\",\"datePublished\":\"2024-05-30T09:17:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#primaryimage\",\"url\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp\",\"contentUrl\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp\",\"width\":1200,\"height\":801},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nayada.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/nayada.eu\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Peeling de caf\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nayada.eu\/es\/#website\",\"url\":\"https:\/\/nayada.eu\/es\/\",\"name\":\"nayada\",\"description\":\"Relax like your life depends on it\",\"publisher\":{\"@id\":\"https:\/\/nayada.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nayada.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nayada.eu\/es\/#organization\",\"name\":\"nayada\",\"url\":\"https:\/\/nayada.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png\",\"contentUrl\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png\",\"width\":100,\"height\":70,\"caption\":\"nayada\"},\"image\":{\"@id\":\"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Peeling de caf\u00e9 - nayada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/","og_locale":"es_ES","og_type":"article","og_title":"Peeling de caf\u00e9","og_description":"Peeling de caf\u00e9 - este jab\u00f3n de caf\u00e9 favorece la circulaci\u00f3n sangu\u00ednea y el drenaje linf\u00e1tico, lo que a su vez mejora la textura, el color y la \u0435\u043b\u0430\u0441\u0442\u0438\u0447\u043d\u0456\u0441\u0442\u044c\ud83d\ude4c\ud83c\udffc de la piel. Para un mejor efecto, le a\u00f1adimos semillas de amapola, que tambi\u00e9n exfolia las c\u00e9lulas muertas y ayuda a renovar el estrato c\u00f3rneo\ud83e\udd29. Y tambi\u00e9n tenemos jab\u00f3n con lufa, es una esponja de origen natural \ud83c\udf3f.  Este jab\u00f3n masajea y exfolia a\u00fan mejor la piel, por lo que es perfecto para quienes gustan de un efecto brillante.  El masaje acelera la circulaci\u00f3n sangu\u00ednea y el flujo linf\u00e1tico, lo que a su vez elimina el exceso de agua del cuerpo, y las c\u00e9lulas reciben m\u00e1s ox\u00edgeno.  Este procedimiento alivia la fatiga, ayuda a calmarse, relajarse y sintonizar con un sue\u00f1o reparador \ud83d\ude34.  Ingredientes:  Aceite de hueso de albaricoque saponificado, aceite de coco, aceite de almendras dulces, aceite de ricino, caf\u00e9 molido, di\u00f3xido de titanio, cacao en polvo, pigmento mineral, mica composici\u00f3n arom\u00e1tica.  Peso: ~100g (el peso del jab\u00f3n puede variar +\/-10g)","og_url":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/","og_site_name":"nayada","og_image":[{"width":1200,"height":801,"url":"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/","url":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/","name":"Peeling de caf\u00e9 - nayada","isPartOf":{"@id":"https:\/\/nayada.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#primaryimage"},"image":{"@id":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#primaryimage"},"thumbnailUrl":"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp","datePublished":"2024-05-30T09:17:29+00:00","breadcrumb":{"@id":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#primaryimage","url":"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp","contentUrl":"https:\/\/nayada.eu\/wp-content\/uploads\/2024\/05\/Nayada-soap-coffeescrub-1200px-jpg.webp","width":1200,"height":801},{"@type":"BreadcrumbList","@id":"https:\/\/nayada.eu\/es\/shop\/peeling-de-cafe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nayada.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/nayada.eu\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Peeling de caf\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/nayada.eu\/es\/#website","url":"https:\/\/nayada.eu\/es\/","name":"nayada","description":"Relax like your life depends on it","publisher":{"@id":"https:\/\/nayada.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nayada.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nayada.eu\/es\/#organization","name":"nayada","url":"https:\/\/nayada.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png","contentUrl":"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png","width":100,"height":70,"caption":"nayada"},"image":{"@id":"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product\/1296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/comments?post=1296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/media\/1097"}],"wp:attachment":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/media?parent=1296"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product_brand?post=1296"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product_cat?post=1296"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product_tag?post=1296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}