{"id":544,"date":"2023-04-05T15:03:13","date_gmt":"2023-04-05T13:03:13","guid":{"rendered":"https:\/\/nayada.eu\/shop\/tarjeta-regalo-reflexologia-podal\/"},"modified":"2026-05-12T18:11:04","modified_gmt":"2026-05-12T16:11:04","slug":"tarjeta-regalo-reflexologia-podal","status":"publish","type":"product","link":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/","title":{"rendered":"Tarjeta Regalo | Reflexolog\u00eda podal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>La reflexolog\u00eda<\/strong> es un m\u00e9todo hol\u00edstico en el que se tratan los puntos reflejos situados en los pies mediante una t\u00e9cnica de masaje especial. <a href=\"https:\/\/nayada.eu\/es\/reflexologia-podal\/\">LEER M\u00c0S &#8230;<\/a><\/p>\n<h3>30 min<\/h3>\n","protected":false},"featured_media":1818,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[45],"product_tag":[47],"class_list":{"0":"post-544","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tarjetas-regalo","7":"product_tag-masaje","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tarjeta Regalo | Reflexolog\u00eda podal - nayada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tarjeta Regalo | Reflexolog\u00eda podal\" \/>\n<meta property=\"og:description\" content=\"La reflexolog\u00eda es un m\u00e9todo hol\u00edstico en el que se tratan los puntos reflejos situados en los pies mediante una t\u00e9cnica de masaje especial. LEER M\u00c0S ... 30 min\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/\" \/>\n<meta property=\"og:site_name\" content=\"nayada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:11:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/\",\"url\":\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/\",\"name\":\"Tarjeta Regalo | Reflexolog\u00eda podal - nayada\",\"isPartOf\":{\"@id\":\"https:\/\/nayada.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif\",\"datePublished\":\"2023-04-05T13:03:13+00:00\",\"dateModified\":\"2026-05-12T16:11:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#primaryimage\",\"url\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif\",\"contentUrl\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif\",\"width\":1748,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nayada.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/nayada.eu\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tarjeta Regalo | Reflexolog\u00eda podal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nayada.eu\/es\/#website\",\"url\":\"https:\/\/nayada.eu\/es\/\",\"name\":\"nayada\",\"description\":\"Relax like your life depends on it\",\"publisher\":{\"@id\":\"https:\/\/nayada.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nayada.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nayada.eu\/es\/#organization\",\"name\":\"nayada\",\"url\":\"https:\/\/nayada.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png\",\"contentUrl\":\"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png\",\"width\":100,\"height\":70,\"caption\":\"nayada\"},\"image\":{\"@id\":\"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tarjeta Regalo | Reflexolog\u00eda podal - nayada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/","og_locale":"es_ES","og_type":"article","og_title":"Tarjeta Regalo | Reflexolog\u00eda podal","og_description":"La reflexolog\u00eda es un m\u00e9todo hol\u00edstico en el que se tratan los puntos reflejos situados en los pies mediante una t\u00e9cnica de masaje especial. LEER M\u00c0S ... 30 min","og_url":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/","og_site_name":"nayada","article_modified_time":"2026-05-12T16:11:04+00:00","og_image":[{"width":1748,"height":1240,"url":"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/","url":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/","name":"Tarjeta Regalo | Reflexolog\u00eda podal - nayada","isPartOf":{"@id":"https:\/\/nayada.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#primaryimage"},"image":{"@id":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#primaryimage"},"thumbnailUrl":"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif","datePublished":"2023-04-05T13:03:13+00:00","dateModified":"2026-05-12T16:11:04+00:00","breadcrumb":{"@id":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#primaryimage","url":"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif","contentUrl":"https:\/\/nayada.eu\/wp-content\/uploads\/2025\/07\/23.avif","width":1748,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/nayada.eu\/es\/shop\/tarjeta-regalo-reflexologia-podal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nayada.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/nayada.eu\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Tarjeta Regalo | Reflexolog\u00eda podal"}]},{"@type":"WebSite","@id":"https:\/\/nayada.eu\/es\/#website","url":"https:\/\/nayada.eu\/es\/","name":"nayada","description":"Relax like your life depends on it","publisher":{"@id":"https:\/\/nayada.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nayada.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nayada.eu\/es\/#organization","name":"nayada","url":"https:\/\/nayada.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png","contentUrl":"https:\/\/nayada.eu\/wp-content\/uploads\/2022\/12\/Nayada-Logo-black_100px.png","width":100,"height":70,"caption":"nayada"},"image":{"@id":"https:\/\/nayada.eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/comments?post=544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/media\/1818"}],"wp:attachment":[{"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product_brand?post=544"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product_cat?post=544"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nayada.eu\/es\/wp-json\/wp\/v2\/product_tag?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}